{"id":96,"date":"2024-12-18T16:45:34","date_gmt":"2024-12-18T15:45:34","guid":{"rendered":"https:\/\/www.physidia.com\/?page_id=96"},"modified":"2026-04-27T10:22:39","modified_gmt":"2026-04-27T08:22:39","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/nehomy.com\/en\/legal-notice\/","title":{"rendered":"Legal Notices"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"96\" class=\"elementor elementor-96\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33464bbf e-flex e-con-boxed e-con e-parent\" data-id=\"33464bbf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1cd5a16b elementor-widget elementor-widget-text-editor\" data-id=\"1cd5a16b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 style=\"text-align: center;\">Legal Notices<\/h1><h2>1. Mentions l\u00e9gales<\/h2><h3><strong>Editeur<\/strong><\/h3><p>Ce site internet est \u00e9dit\u00e9 par la soci\u00e9t\u00e9 PHYSIDIA, soci\u00e9t\u00e9 par actions simplifi\u00e9e, au capital social de <br \/>20 154 490,00 euros, immatricul\u00e9e au Registre du Commerce et des Soci\u00e9t\u00e9s d\u2019Angers sous le num\u00e9ro 528 454 028.<\/p><p>Adresse du si\u00e8ge social : 11-13, Boulevard des Bretonni\u00e8res, 49124 Saint Barth\u00e9l\u00e9my-d\u2019Anjou ;<\/p><p>T\u00e9l\u00e9phone : +33(0) 241 731 008 ;<br \/>Adresse email : <a href=\"mailto:contact@nehomy.com\">contact@nehomy.com<\/a>;<br \/>N\u00b0 SIRET\u00a0: 52845402800028<br \/>N\u00b0 TVA intracommunautaire\u00a0: FR13528454028<\/p><h3><strong>Directeur de publication<\/strong><\/h3><p>Dugas Ga\u00ebtan, Directeur Commercial et Marketing<br \/>Giroud Aurore, Chef de Projet<\/p><h2>2. Objet du site<\/h2><p>Le site <a href=\"https:\/\/nehomy.com\/en\/\">www.nehomy.com<\/a> est un site purement institutionnel dont l\u2019objet est de mettre en avant les t\u00e9moignages de patients b\u00e9n\u00e9ficiant de soins d\u2019h\u00e9modialyse \u00e0 domicile.<\/p><h2>3. Droit d\u2019auteur et propri\u00e9t\u00e9 intellectuelle<\/h2><h3><strong>Marque et logo<\/strong><\/h3><p>Les marques et logos figurant sur le site\u00a0<a href=\"https:\/\/nehomy.com\/en\/\">www.nehomy.com<\/a> sont des marques et logos d\u00e9pos\u00e9s. Toute reproduction, imitation, utilisation totale ou partielle de ces marques et logos sans l\u2019autorisation pr\u00e9alable et expresse de PHYSIDIA est interdite.\u00a0<\/p><h3><strong>Contenu du site<\/strong><\/h3><p>Le site et son contenu, y compris, mais sans s\u2019y limiter, l\u2019architecture\/arborescence du site, tous les textes, graphiques, photographies, images (anim\u00e9es ou non), illustrations, articles, lettres d\u2019information, communiqu\u00e9s de presse, pr\u00e9sentations, brochures, bases de donn\u00e9es (incluant ou non des donn\u00e9es personnelles), ainsi que leur assemblage et\/ou leur ergonomie, sont et resteront la propri\u00e9t\u00e9 exclusive de PHYSIDIA. Le site et son contenu sont prot\u00e9g\u00e9s par la loi fran\u00e7aise et les conventions internationales sur le droit d\u2019auteur. Le site et\/ou son contenu ne peuvent \u00eatre copi\u00e9s, reproduits, publi\u00e9s, t\u00e9l\u00e9charg\u00e9s, transmis, vendus ou distribu\u00e9s, en tout ou partie, \u00e0 titre gratuit ou on\u00e9reux, par quelque proc\u00e9d\u00e9 que ce soit, sous quelque forme ou support que ce soit et \u00e0 quelque fin que ce soit.<\/p><p>Toute copie, reproduction, adaptation, publication, t\u00e9l\u00e9chargement, imitation, transfert, transmission ou distribution, en tout ou en partie, du site web et de son contenu constitue un acte de violation des droits de propri\u00e9t\u00e9 intellectuelle de PHYSIDIA et sera poursuivi en tant que tel devant les tribunaux comp\u00e9tents.<\/p><p>Chaque utilisateur est seul responsable de l\u2019utilisation qu\u2019il fait des informations fournies sur le site et PHYSIDIA ne peut \u00eatre tenu responsable de tout dommage direct ou indirect r\u00e9sultant de l\u2019utilisation de ces informations par l\u2019utilisateur. Le site web est accessible 7 jours sur 7, 24 heures sur 24, sous r\u00e9serve des interruptions n\u00e9cessaires aux op\u00e9rations de maintenance, d\u2019entretien et de mise \u00e0 jour technique que PHYSIDIA jugera utile d\u2019effectuer.\u00a0<\/p><h2>4. Liens hypertextes<\/h2><p>Le site peut comporter des liens hypertextes vers des sites tiers. Toute consultation de sites tiers \u00e0 l\u2019aide des liens hypertextes mis \u00e0 disposition sur le site s\u2019effectue \u00e0 la convenance et aux risques et p\u00e9rils de l\u2019utilisateur. PHYSIDIA ne peut \u00eatre tenu responsable de quelque mani\u00e8re que ce soit en raison de ces liens hypertextes. PHYSIDIA ne cautionne ni ne fait aucune d\u00e9claration concernant ces sites ou les informations ou documents qu\u2019ils contiennent, ni les r\u00e9sultats qui peuvent \u00eatre obtenus lors de leur consultation. Nous vous recommandons de lire leurs conditions g\u00e9n\u00e9rales d\u2019utilisation. La cr\u00e9ation d\u2019un lien hypertexte vers le site\u00a0<a href=\"https:\/\/nehomy.com\/en\/\">www.nehomy.com<\/a> n\u00e9cessite l\u2019accord pr\u00e9alable et expr\u00e8s de PHYSIDIA.<\/p><h2>5. Limite de responsabilit\u00e9<\/h2><p>L\u2019utilisateur reconna\u00eet express\u00e9ment utiliser le site <a href=\"https:\/\/nehomy.com\/en\/\">www.nehomy.com<\/a> \u00e0 ses propres risques et sous sa responsabilit\u00e9 exclusive. Le site <a href=\"https:\/\/nehomy.com\/en\/\">www.nehomy.com<\/a> est fourni en l&rsquo;\u00e9tat, accessible selon sa disponibilit\u00e9 et sans aucune garantie pr\u00e9alable de la part de l&rsquo;\u00e9diteur.<\/p><p>L&rsquo;\u00e9diteur s&rsquo;efforce d&rsquo;assurer l&rsquo;exactitude et la mise \u00e0 jour des informations diffus\u00e9es sur ce site, dont il se r\u00e9serve le droit de corriger, \u00e0 tout moment et sans pr\u00e9avis, le contenu. Toutefois, l&rsquo;\u00e9diteur ne peut garantir, d\u00e9clarer ou assurer l&rsquo;exactitude, la pr\u00e9cision ou l&rsquo;exhaustivit\u00e9 des informations mises \u00e0 disposition sur ce site.<\/p><p>L\u2019\u00e9diteur n\u2019est pas responsable des dommages, qu\u2019elles qu\u2019en soient les causes, origines, natures ou cons\u00e9quences, provoqu\u00e9s \u00e0 raison de l\u2019acc\u00e8s de l\u2019utilisateur au site ou de l&rsquo;impossibilit\u00e9 d&rsquo;y acc\u00e9der, de m\u00eame que l&rsquo;utilisation du site et\/ou du cr\u00e9dit accord\u00e9 \u00e0 une quelconque information provenant directement ou indirectement de ce dernier.<\/p><h2>6. Traitement des donn\u00e9es \u00e0 caract\u00e8re personnel<\/h2><p>Les informations relatives au traitement des donn\u00e9es personnelles sont disponibles dans la Politique de confidentialit\u00e9 disponible sur le site <a href=\"https:\/\/nehomy.com\/en\/\">www.nehomy.com<\/a>.<\/p><h2>7. Contact<\/h2><p>Pour tout renseignement concernant le site et ses contenus, vous pouvez contacter PHYSIDIA dans l\u2019onglet Contact via le formulaire de contact ou par email \u00e0 l\u2019adresse suivante : <a href=\"mailto:contact@nehomy.com\">contact@nehomy.com<\/a>.<\/p><h2>8. H\u00e9bergement du site<\/h2><p>Le site <a class=\"LinkThemeablePresentation LinkPrimaryPresentation LinkPrimaryPresentation--sentimentSelected PrimaryLink HighlightSol HighlightSol--core HighlightSol--buildingBlock\" href=\"https:\/\/nehomy.com\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.nehomy.com<\/a> est h\u00e9berg\u00e9 par la soci\u00e9t\u00e9 Microsoft France, SAS, au capital social de 4\u00a0240\u00a0000,00 euros, immatricul\u00e9e au Registre du Commerce et des Soci\u00e9t\u00e9s de Nanterre, sous le num\u00e9ro 32773318400516, dont le si\u00e8ge social est situ\u00e9 37\/45 Quai du Pr\u00e9sident Roosevelt 92130 Issy-les-Moulineaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mentions l\u00e9gales 1. Mentions l\u00e9gales Editeur Ce site internet est \u00e9dit\u00e9 par la soci\u00e9t\u00e9 PHYSIDIA, soci\u00e9t\u00e9 par actions simplifi\u00e9e, au capital social de 20 154 490,00 euros, immatricul\u00e9e au Registre du Commerce et des Soci\u00e9t\u00e9s d\u2019Angers sous le num\u00e9ro 528 454 028. Adresse du si\u00e8ge social : 11-13, Boulevard des Bretonni\u00e8res, 49124 Saint Barth\u00e9l\u00e9my-d\u2019Anjou ; T\u00e9l\u00e9phone : +33(0) 241 731 008 ;Adresse email : contact@nehomy.com;N\u00b0 SIRET\u00a0: 52845402800028N\u00b0 TVA intracommunautaire\u00a0: FR13528454028 Directeur de publication Dugas Ga\u00ebtan, Directeur Commercial et MarketingGiroud Aurore, Chef de Projet 2. Objet du site Le site www.nehomy.com est un site purement institutionnel dont l\u2019objet est de mettre en avant les t\u00e9moignages de patients b\u00e9n\u00e9ficiant de soins d\u2019h\u00e9modialyse \u00e0 domicile. 3. Droit d\u2019auteur et propri\u00e9t\u00e9 intellectuelle Marque et logo Les marques et logos figurant sur le site\u00a0www.nehomy.com sont des marques et logos d\u00e9pos\u00e9s. Toute reproduction, imitation, utilisation totale ou partielle de ces marques et logos sans l\u2019autorisation pr\u00e9alable [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-96","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mentions l\u00e9gales - Nehomy - H\u00e9modialyse \u00e0 domicile<\/title>\n<meta name=\"description\" content=\"Mentions l\u00e9gales du site Nehomy : informations juridiques, droits d\u2019auteur, responsabilit\u00e9, h\u00e9bergement et RGPD.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nehomy.com\/en\/legal-notice\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentions l\u00e9gales\" \/>\n<meta property=\"og:description\" content=\"Mentions l\u00e9gales du site Nehomy : informations juridiques, droits d\u2019auteur, responsabilit\u00e9, h\u00e9bergement et RGPD.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nehomy.com\/en\/legal-notice\/\" \/>\n<meta property=\"og:site_name\" content=\"Nehomy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nehomy\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T08:22:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nehomy.com\\\/mentions-legales\\\/\",\"url\":\"https:\\\/\\\/nehomy.com\\\/mentions-legales\\\/\",\"name\":\"Mentions l\u00e9gales - Nehomy - H\u00e9modialyse \u00e0 domicile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nehomy.com\\\/#website\"},\"datePublished\":\"2024-12-18T15:45:34+00:00\",\"dateModified\":\"2026-04-27T08:22:39+00:00\",\"description\":\"Mentions l\u00e9gales du site Nehomy : informations juridiques, droits d\u2019auteur, responsabilit\u00e9, h\u00e9bergement et RGPD.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nehomy.com\\\/mentions-legales\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nehomy.com\\\/mentions-legales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nehomy.com\\\/mentions-legales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/nehomy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mentions l\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nehomy.com\\\/#website\",\"url\":\"https:\\\/\\\/nehomy.com\\\/\",\"name\":\"Nehomy | H\u00e9modialyse \u00e0 Domicile\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/nehomy.com\\\/#organization\"},\"alternateName\":\"Nehomy | HDDQ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nehomy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nehomy.com\\\/#organization\",\"name\":\"Nehomy\",\"alternateName\":\"Nehomy\",\"url\":\"https:\\\/\\\/nehomy.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/nehomy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nehomy.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/nehomy-favicon-32x32-1.svg\",\"contentUrl\":\"https:\\\/\\\/nehomy.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/nehomy-favicon-32x32-1.svg\",\"width\":1,\"height\":1,\"caption\":\"Nehomy\"},\"image\":{\"@id\":\"https:\\\/\\\/nehomy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nehomy\"],\"email\":\"contact@nehomy.com\",\"legalName\":\"Physidia S.A.S.\",\"foundingDate\":\"2010-11-01\",\"taxID\":\"528 454 028 00028\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/nehomy.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/nehomy.com\\\/politique-de-confidentialite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mentions l\u00e9gales - Nehomy - H\u00e9modialyse \u00e0 domicile","description":"Mentions l\u00e9gales du site Nehomy : informations juridiques, droits d\u2019auteur, responsabilit\u00e9, h\u00e9bergement et RGPD.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nehomy.com\/en\/legal-notice\/","og_locale":"en_GB","og_type":"article","og_title":"Mentions l\u00e9gales","og_description":"Mentions l\u00e9gales du site Nehomy : informations juridiques, droits d\u2019auteur, responsabilit\u00e9, h\u00e9bergement et RGPD.","og_url":"https:\/\/nehomy.com\/en\/legal-notice\/","og_site_name":"Nehomy","article_publisher":"https:\/\/www.facebook.com\/Nehomy","article_modified_time":"2026-04-27T08:22:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nehomy.com\/mentions-legales\/","url":"https:\/\/nehomy.com\/mentions-legales\/","name":"Mentions l\u00e9gales - Nehomy - H\u00e9modialyse \u00e0 domicile","isPartOf":{"@id":"https:\/\/nehomy.com\/#website"},"datePublished":"2024-12-18T15:45:34+00:00","dateModified":"2026-04-27T08:22:39+00:00","description":"Mentions l\u00e9gales du site Nehomy : informations juridiques, droits d\u2019auteur, responsabilit\u00e9, h\u00e9bergement et RGPD.","breadcrumb":{"@id":"https:\/\/nehomy.com\/mentions-legales\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nehomy.com\/mentions-legales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nehomy.com\/mentions-legales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/nehomy.com\/"},{"@type":"ListItem","position":2,"name":"Mentions l\u00e9gales"}]},{"@type":"WebSite","@id":"https:\/\/nehomy.com\/#website","url":"https:\/\/nehomy.com\/","name":"Nehomy | H\u00e9modialyse \u00e0 Domicile","description":"","publisher":{"@id":"https:\/\/nehomy.com\/#organization"},"alternateName":"Nehomy | HDDQ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nehomy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/nehomy.com\/#organization","name":"Nehomy","alternateName":"Nehomy","url":"https:\/\/nehomy.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/nehomy.com\/#\/schema\/logo\/image\/","url":"https:\/\/nehomy.com\/wp-content\/uploads\/2024\/12\/nehomy-favicon-32x32-1.svg","contentUrl":"https:\/\/nehomy.com\/wp-content\/uploads\/2024\/12\/nehomy-favicon-32x32-1.svg","width":1,"height":1,"caption":"Nehomy"},"image":{"@id":"https:\/\/nehomy.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nehomy"],"email":"contact@nehomy.com","legalName":"Physidia S.A.S.","foundingDate":"2010-11-01","taxID":"528 454 028 00028","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/nehomy.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/nehomy.com\/politique-de-confidentialite\/"}]}},"_links":{"self":[{"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/pages\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/comments?post=96"}],"version-history":[{"count":43,"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/pages\/96\/revisions"}],"predecessor-version":[{"id":7962,"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/pages\/96\/revisions\/7962"}],"wp:attachment":[{"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/media?parent=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}