{"id":91,"date":"2024-12-18T16:45:09","date_gmt":"2024-12-18T15:45:09","guid":{"rendered":"https:\/\/www.physidia.com\/?page_id=91"},"modified":"2026-03-19T16:12:58","modified_gmt":"2026-03-19T15:12:58","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/nehomy.com\/en\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"91\" class=\"elementor elementor-91\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a00333a e-flex e-con-boxed e-con e-parent\" data-id=\"a00333a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-387f4f8 elementor-widget elementor-widget-text-editor\" data-id=\"387f4f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 style=\"text-align: center;\">Politique de confidentialit\u00e9<\/h1><h2>1. PREAMBULE<\/h2><p>La soci\u00e9t\u00e9 PHYSIDIA est une soci\u00e9t\u00e9 par actions simplifi\u00e9e, sp\u00e9cialis\u00e9e dans la dialyse \u00e0 domicile.<\/p><p>La pr\u00e9sente politique de confidentialit\u00e9 (ci-apr\u00e8s la \u00ab <strong>Politique<\/strong> \u00bb) a pour objet d\u2019informer les utilisateurs (ci-apr\u00e8s d\u00e9sign\u00e9s \u00ab <strong>Utilisateurs<\/strong> \u00bb) du site internet <a href=\"https:\/\/nehomy.com\/\">www.nehomy.com<\/a> (ci-apr\u00e8s le \u00ab <strong>Site<\/strong> \u00bb) sur les conditions de collecte et de traitement de leurs donn\u00e9es \u00e0 caract\u00e8re personnel (ci-apr\u00e8s les \u00ab\u00a0<strong>Donn\u00e9es Personnelles\u00a0<\/strong>\u00bb) dans le cadre de l\u2019utilisation du Site, y compris lorsque l\u2019Utilisateur cr\u00e9e un compte et renseigne certaines informations le concernant.<\/p><p>Cette Politique a \u00e9t\u00e9 \u00e9labor\u00e9e de mani\u00e8re \u00e0 garantir que PHYSIDIA exerce ses activit\u00e9s conform\u00e9ment aux l\u00e9gislations nationales, europ\u00e9ennes et internationales relatives \u00e0 la protection des Donn\u00e9es Personnelles et, en particulier, le R\u00e8glement (UE) n\u00b0 2016\/679 du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de ces donn\u00e9es, et abrogeant la directive 95\/46\/CE (dit \u00ab <strong>R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es<\/strong> \u00bb ou \u00ab <strong>RGPD<\/strong> \u00bb) et la loi fran\u00e7aise n\u00b0 78-17 du 6 janvier 1978 modifi\u00e9e, relative \u00e0 l\u2019informatique, aux fichiers et aux libert\u00e9s (la \u00ab <strong>Loi Informatique et Libert\u00e9s<\/strong> \u00bb) (ensemble la <br \/>\u00ab<strong> R\u00e9glementation Applicable <\/strong>\u00bb).<\/p><h3><strong>1.1. Contr\u00f4le<\/strong><strong>\u00a0<\/strong><\/h3><p>PHYSIDIA effectue tous les contr\u00f4les n\u00e9cessaires afin de mettre en \u0153uvre sa conformit\u00e9 \u00e0 la R\u00e9glementation Applicable.<\/p><p>Pour toute question en mati\u00e8re de donn\u00e9es personnelles, PHYSIDIA peut \u00eatre contact\u00e9e par courriel \u00e0 l\u2019adresse suivante : <a href=\"mailto:contact@nehomy.com\">contact@nehomy.com<\/a>.<\/p><h3><strong>1.2. D\u00e9finitions<\/strong><\/h3><p>Afin de mieux comprendre les notions utilis\u00e9es dans la Politique, le RGPD a propos\u00e9 un certain nombre de d\u00e9finitions des termes couramment employ\u00e9s en mati\u00e8re de protection des donn\u00e9es personnelles.<\/p><p>Les d\u00e9finitions des termes employ\u00e9s dans la pr\u00e9sente Politique de confidentialit\u00e9 sont notamment issues de l\u2019article 4 du RGPD.<\/p><h2>2. PRINCIPES DE PROTECTION DES DONNEES PERSONNELLES<\/h2><p>La pr\u00e9sente Politique est fond\u00e9e sur le respect des principes d\u00e9crits ci-apr\u00e8s, pos\u00e9s par la R\u00e9glementation Applicable.<\/p><p>En tant que Responsable des traitements qu\u2019elle met en \u0153uvre dans le cadre notamment de la gestion du Site, et notamment via l\u2019onglet de contact disponible sur le Site, PHYSIDIA est responsable du respect de ces principes et doit \u00eatre en mesure de d\u00e9montrer \u00e0 tout moment leur respect.<\/p><p>La mise en \u0153uvre et le respect de ces principes sont essentiels et doivent \u00eatre contr\u00f4l\u00e9s r\u00e9guli\u00e8rement par les personnes qui sont responsables des probl\u00e9matiques li\u00e9es au Traitement de Donn\u00e9es Personnelles au sein de PHYSIDIA.<\/p><h3><strong>2.1. Lic\u00e9it\u00e9, loyaut\u00e9 et transparence<\/strong><\/h3><p>Les Donn\u00e9es Personnelles doivent \u00eatre trait\u00e9es de mani\u00e8re licite, loyale et transparente au regard de la Personne Concern\u00e9e par le Traitement de Donn\u00e9es Personnelles.<\/p><h3><strong>2.2. Limitation des finalit\u00e9s<\/strong><\/h3><p>Les Donn\u00e9es Personnelles doivent \u00eatre trait\u00e9es pour des finalit\u00e9s d\u00e9termin\u00e9es, explicites et l\u00e9gitimes, et ne pas \u00eatre trait\u00e9es ult\u00e9rieurement d&rsquo;une mani\u00e8re incompatible avec ces finalit\u00e9s.<\/p><h3><strong>2.3. Minimisation des donn\u00e9es<\/strong><\/h3><p>Les Donn\u00e9es Personnelles doivent \u00eatre ad\u00e9quates, pertinentes et limit\u00e9es \u00e0 ce qui est n\u00e9cessaire au regard des finalit\u00e9s pour lesquelles elles sont trait\u00e9es.<\/p><h3><strong>2.4. Exactitude<\/strong><\/h3><p>Les Donn\u00e9es Personnelles doivent \u00eatre exactes et, si n\u00e9cessaire, tenues \u00e0 jour ; toutes les mesures raisonnables doivent \u00eatre prises pour que les Donn\u00e9es Personnelles qui sont inexactes, eu \u00e9gard aux finalit\u00e9s pour lesquelles elles sont trait\u00e9es, soient effac\u00e9es ou rectifi\u00e9es sans tarder.<\/p><h3><strong>2.5. Limitation de la conservation<\/strong><\/h3><p>Les Donn\u00e9es Personnelles doivent \u00eatre conserv\u00e9es sous une forme permettant l&rsquo;identification des Personnes Concern\u00e9es pendant une dur\u00e9e n&rsquo;exc\u00e9dant pas celle n\u00e9cessaire au regard des finalit\u00e9s pour lesquelles elles sont trait\u00e9es. Elles peuvent \u00eatre conserv\u00e9es pour des dur\u00e9es plus longues dans la mesure o\u00f9 elles seront trait\u00e9es exclusivement \u00e0 des fins archivistiques dans l&rsquo;int\u00e9r\u00eat public, \u00e0 des fins de recherche scientifique ou historique ou \u00e0 des fins statistiques, pour autant que soient mises en \u0153uvre des mesures techniques et organisationnelles appropri\u00e9es afin de garantir les droits et libert\u00e9s de la personne concern\u00e9e.<\/p><h3><strong>2.6. Int\u00e9grit\u00e9 et confidentialit\u00e9<\/strong><\/h3><p>Les Donn\u00e9es Personnelles doivent \u00eatre trait\u00e9es de fa\u00e7on \u00e0 garantir une s\u00e9curit\u00e9 appropri\u00e9e, y compris la protection contre le Traitement non autoris\u00e9 ou illicite et contre la perte, la destruction ou les d\u00e9g\u00e2ts d&rsquo;origine accidentelle, \u00e0 l&rsquo;aide de mesures techniques ou organisationnelles appropri\u00e9es.<\/p><h2>3. DONNEES PERSONNELLES TRAITEES PAR PHYSIDIA<\/h2><h3><strong>3.1. Donn\u00e9es collect\u00e9es dans le cadre de l\u2019utilisation du Site<\/strong><\/h3><p>Les Donn\u00e9es Personnelles collect\u00e9es et trait\u00e9es par PHYSIDIA en tant que Responsable de Traitement sont celles susceptibles d\u2019\u00eatre collect\u00e9es dans le cadre de l\u2019utilisation du Site par l\u2019Utilisateur, et pr\u00e9cis\u00e9ment dans le cadre de la cr\u00e9ation d\u2019un \u00ab\u00a0compte\u00a0\u00bb.<\/p><p>Les Donn\u00e9es Personnelles des Utilisateurs qui peuvent \u00eatre trait\u00e9es par PHYSIDIA sont des donn\u00e9es d\u2019identification des Utilisateurs, \u00e0 savoir :<span style=\"background-color: transparent;\">.<\/span><\/p><ul><li>Etat civil (nom, pr\u00e9nom) ;<\/li><li>Coordonn\u00e9es personnelles (adresse postale, adresse e-mail, num\u00e9ro de t\u00e9l\u00e9phone) ;<\/li><li>Le statut de l\u2019Utilisateur (\u00e0 savoir Patient, Proche aidant, Membre de la famille, Autre)<\/li><li>Si l\u2019Utilisateur est un patient : Stade de l\u2019insuffisance r\u00e9nale.<\/li><li>Toute autre Donn\u00e9e transmise par un Utilisateur dans le cadre d\u2019une prise de contact<\/li><\/ul><p>Ces Donn\u00e9es Personnelles sont collect\u00e9es lors du processus de cr\u00e9ation de compte r\u00e9alis\u00e9 par l\u2019Utilisateur sur le Site.<\/p><p>Les informations relatives \u00e0 l\u2019\u00e9tat de sant\u00e9 de l\u2019Utilisateur constituent des donn\u00e9es de sant\u00e9 au sens du RGPD. Elles sont renseign\u00e9es volontairement et d\u00e9clarativement par l\u2019Utilisateur lorsqu\u2019il se d\u00e9clare patient, et sont strictement limit\u00e9es \u00e0 ce qui est n\u00e9cessaire pour lui permettre d\u2019acc\u00e9der \u00e0 des contenus ou services adapt\u00e9s propos\u00e9s sur le Site. Ces donn\u00e9es de sant\u00e9 ne sont pas utilis\u00e9es \u00e0 des fins de diagnostic, de suivi m\u00e9dical ou de prise en charge th\u00e9rapeutique.<\/p><p>Par ailleurs, PHYSIDIA collecte et traite les Donn\u00e9es Personnelles suivantes :<\/p><ul><li>\u00a0Les donn\u00e9es de connexion de l\u2019Utilisateur, telles que l\u2019adresse IP, le syst\u00e8me d\u2019exploitation utilis\u00e9 ou le type de navigateur ;<\/li><li>Les donn\u00e9es contenues dans un fichier de journalisation (date et heure de connexion, actions r\u00e9alis\u00e9es).<\/li><\/ul><h3><strong>3.2. Finalit\u00e9s des traitements des Donn\u00e9es<\/strong><\/h3><p>PHYSIDIA agit comme Responsable de Traitement des Donn\u00e9es Personnelles des Utilisateurs dans le cadre de l\u2019utilisation et de la gestion du Site, dont notamment la cr\u00e9ation de compte par les Utilisateurs.<\/p><p>PHYSIDIA collecte et traite les Donn\u00e9es Personnelles des Utilisateurs pour les finalit\u00e9s suivantes :<\/p><ul><li>Prise de contact des Utilisateurs aupr\u00e8s de PHYSIDIA ;<\/li><li>Cr\u00e9ation et gestion du compte Utilisateur, selon le profil renseign\u00e9 (patient ou autre) ;<\/li><li>Inscription \u00e0 la Newsletter de PHYSIDIA\u00a0;<\/li><li>R\u00e9aliser des statistiques afin d\u2019am\u00e9liorer les fonctionnalit\u00e9s et la performance du Site et conna\u00eetre la mani\u00e8re dont l\u2019Utilisateur utilise le Site de PHYSIDIA.<\/li><\/ul><p>Les finalit\u00e9s poursuivies sont exclusivement informatives, p\u00e9dagogiques et organisationnelles et n\u2019impliquent aucun traitement de nature m\u00e9dicale.<\/p><p>Pour plus d\u2019informations, nous vous invitons \u00e0 consulter la Politique de cookies de PHYSIDIA \u00e0 l\u2019adresse suivante : <a href=\"https:\/\/nehomy.com\/politique-de-gestion-des-cookies\/\">politique de gestion des cookies<\/a>.<\/p><p>Les Donn\u00e9es Personnelles des Utilisateurs sont strictement confidentielles et sont trait\u00e9es par PHYSIDIA pour les seules finalit\u00e9s d\u00e9crites ci-dessus.<\/p><p>PHYSIDIA s\u2019engage express\u00e9ment \u00e0 ne pas traiter ult\u00e9rieurement les Donn\u00e9es Personnelles pour des finalit\u00e9s incompatibles avec les finalit\u00e9s susvis\u00e9es.<\/p><p>Par ailleurs, PHYSIDIA s\u2019engage \u00e0 ne pas divulguer, c\u00e9der, louer ou transmettre les Donn\u00e9es Personnelles des Utilisateurs \u00e0 des tiers autres que l\u2019h\u00e9bergeur des Donn\u00e9es du Site.<\/p><h3><strong>3.3. Base(s) l\u00e9gale(s) du Traitement des Donn\u00e9es<\/strong><\/h3><p>PHYSIDIA agit en qualit\u00e9 de Responsable de Traitement au sens de la R\u00e9glementation Applicable lorsqu\u2019elle traite les Donn\u00e9es Personnelles des Utilisateurs dans le cadre de l\u2019utilisation du Site et notamment de la cr\u00e9ation d\u2019un compte par l\u2019Utilisateur.<\/p><p>Les traitements de Donn\u00e9es Personnelles mis en \u0153uvre par PHYSIDIA reposent sur les bases l\u00e9gales suivantes :<\/p><ul><li>Le consentement de l\u2019Utilisateur, conform\u00e9ment \u00e0 l\u2019article 6, 1, a) du RGPD, pour la cr\u00e9ation de compte, la prise de contact et l\u2019inscription \u00e0 la newsletter ;<\/li><li>Le consentement explicite de l\u2019Utilisateur, conform\u00e9ment \u00e0 l\u2019article 9, 2, a) du RGPD, lorsque le traitement porte sur des donn\u00e9es de sant\u00e9.<\/li><\/ul><p>Ces consentements sont recueillis de mani\u00e8re libre, sp\u00e9cifique, \u00e9clair\u00e9e et univoque, notamment au moyen de cases \u00e0 cocher distinctes lors de la cr\u00e9ation du compte.<\/p><h3><strong>3.4. Dur\u00e9e de conservation des Donn\u00e9es<\/strong><\/h3><p><strong>\u00a0<\/strong>Les Donn\u00e9es Personnelles collect\u00e9es par PHYSIDIA sont conserv\u00e9es pendant une dur\u00e9e n\u2019exc\u00e9dant pas celle strictement n\u00e9cessaire \u00e0 la r\u00e9alisation des finalit\u00e9s pour lesquelles elles sont trait\u00e9es, conform\u00e9ment \u00e0 la R\u00e9glementation Applicable.<\/p><p>Lorsque l\u2019Utilisateur cr\u00e9e un compte sur le Site, les Donn\u00e9es Personnelles associ\u00e9es \u00e0 ce compte sont conserv\u00e9es pendant toute la dur\u00e9e d\u2019activation du compte. En cas d\u2019inactivit\u00e9 du compte, ces Donn\u00e9es sont conserv\u00e9es pour une dur\u00e9e maximale de trois (3) ans \u00e0 compter de la derni\u00e8re interaction de l\u2019Utilisateur avec PHYSIDIA.<\/p><p>\u00c0 l\u2019issue de ces dur\u00e9es, les Donn\u00e9es Personnelles sont soit supprim\u00e9es, soit archiv\u00e9es pour la dur\u00e9e n\u00e9cessaire au respect des obligations l\u00e9gales et r\u00e9glementaires de PHYSIDIA ou aux fins de constatation, d\u2019exercice ou de d\u00e9fense d\u2019un droit en justice, puis supprim\u00e9es \u00e0 l\u2019expiration de cette dur\u00e9e d\u2019archivage.<\/p><h2>4. HEBERGEMENT DU SITE DE PHYSIDIA<\/h2><p>PHYSIDIA a recours \u00e0 un prestataire externe pour l\u2019h\u00e9bergement du Site et des Donn\u00e9es Personnelles qu\u2019il contient.<\/p><p>L\u2019h\u00e9bergeur agit en qualit\u00e9 de sous-traitant au sens du RGPD, conform\u00e9ment aux instructions de PHYSIDIA, et pr\u00e9sente des garanties suffisantes en mati\u00e8re de s\u00e9curit\u00e9 et de confidentialit\u00e9 des Donn\u00e9es Personnelles.<\/p><p>L\u2019h\u00e9bergeur du Site est un h\u00e9bergeur de donn\u00e9es de sant\u00e9 certifi\u00e9 HDS au sens de l\u2019article L. 1111-8 du Code de la sant\u00e9 publique, pr\u00e9sentant des garanties suffisantes en mati\u00e8re de s\u00e9curit\u00e9 et de confidentialit\u00e9 des Donn\u00e9es Personnelles, et notamment des donn\u00e9es de sant\u00e9.<\/p><p>Les serveurs de l\u2019h\u00e9bergeur [nom] sont situ\u00e9s en FRANCE.<\/p><h2>5. MESURES DE SECURITE DES DONNEES PERSONNELLES<\/h2><p>PHYSIDIA s\u2019engage \u00e0 prot\u00e9ger les Donn\u00e9es Personnelles des Utilisateurs par des mesures de s\u00e9curit\u00e9 techniques renforc\u00e9es.<\/p><p>En tant que Responsable de traitement, PHYSIDIA met en \u0153uvre des mesures de s\u00e9curit\u00e9 techniques et organisationnelles conformes \u00e0 la R\u00e9glementation Applicable et aux standards de l\u2019industrie, de mani\u00e8re \u00e0 assurer la protection des Donn\u00e9es trait\u00e9es par le Responsable de Traitement contre leur destruction, perte, alt\u00e9ration, divulgation \u00e0 des tiers non autoris\u00e9s, pour assurer le r\u00e9tablissement de la disponibilit\u00e9 des Donn\u00e9es Personnelles et l&rsquo;acc\u00e8s \u00e0 celles-ci dans des d\u00e9lais appropri\u00e9s en cas d&rsquo;incident physique ou technique.<\/p><p>Lorsque des donn\u00e9es de sant\u00e9 sont trait\u00e9es, PHYSIDIA met en \u0153uvre des mesures de s\u00e9curit\u00e9 renforc\u00e9es, adapt\u00e9es \u00e0 la sensibilit\u00e9 de ces donn\u00e9es, conform\u00e9ment aux exigences du RGPD.<\/p><p>L\u2019Utilisateur doit toutefois \u00eatre conscient que malgr\u00e9 toutes les mesures de s\u00e9curit\u00e9 mises en \u0153uvre, aucune transmission de Donn\u00e9es sur Internet n\u2019est s\u00e9curis\u00e9e \u00e0 100 % et que toutes les informations communiqu\u00e9es en ligne peuvent \u00eatre potentiellement intercept\u00e9es et utilis\u00e9es par d\u2019autres personnes que le Destinataire souhait\u00e9.<\/p><p>En cas de recours \u00e0 un Sous-traitant, PHYSIDIA s\u2019assure que ce dernier respecte ses obligations en mati\u00e8re de s\u00e9curit\u00e9 pr\u00e9alablement \u00e0 toute communication de Donn\u00e9es.<\/p><h2>6.DROITS DES UTILISATEURS SUR LEURS DONNEES PERSONNELLES<\/h2><p>Conform\u00e9ment \u00e0 la R\u00e9glementation Applicable, tout Utilisateur dispose de droits sur les Donn\u00e9es Personnelles le concernant trait\u00e9es par PHYSIDIA.<\/p><p>L\u2019Utilisateur peut exercer ses droits ou poser toute question relative \u00e0 la protection de ses Donn\u00e9es Personnelles aupr\u00e8s de PHYSIDIA, \u00e0 l\u2019adresse suivante : <a href=\"mailto:dpo@physidia.fr\">dpo@physidia.fr<\/a>. L\u2019Utilisateur est invit\u00e9 \u00e0 indiquer pr\u00e9cis\u00e9ment l\u2019objet de sa demande et les Donn\u00e9es Personnelles concern\u00e9es.<\/p><p>Ces droits sont les suivants :<\/p><ul><li>Droit d\u2019acc\u00e8s aux Donn\u00e9es qui le concernent et aux informations relatives au Traitement (finalit\u00e9s, cat\u00e9gorie de Donn\u00e9es concern\u00e9es, Destinataires, dur\u00e9e de conservation, etc.) ;<\/li><li>Droit de rectification de ses Donn\u00e9es Personnelles en cas d\u2019information erron\u00e9e ou <br \/>incompl\u00e8te ;<\/li><li>Droit \u00e0 l\u2019effacement (droit \u00e0 l\u2019oubli) de ses Donn\u00e9es Personnelles qui ne seraient plus n\u00e9cessaires au regard des finalit\u00e9s poursuivies, ou (ii) pour lesquelles l\u2019Utilisateur a exerc\u00e9 son droit d\u2019opposition au Traitement ;<\/li><li>Droit au retrait du consentement de ses Donn\u00e9es Personnelles qui permet \u00e0 l\u2019Utilisateur de retirer son consentement \u00e0 tout moment en informant PHYSIDIA par le biais d\u2019un e-mail ;<\/li><li>Droit \u00e0 la limitation du Traitement de ses Donn\u00e9es Personnelles, lorsque (i) l\u2019Utilisateur conteste leur exactitude ou (ii) lorsque le d\u00e9lai de conservation des Donn\u00e9es est arriv\u00e9 \u00e0 son terme mais que l\u2019Utilisateur a besoin de conserver ces Donn\u00e9es pour la constatation, l\u2019exercice ou la d\u00e9fense d\u2019un droit en justice ou (iii) lorsque l\u2019Utilisateur s\u2019oppose \u00e0 l\u2019un des Traitements de ses Donn\u00e9es Personnelles ;<\/li><li>Droit \u00e0 la portabilit\u00e9 de ses Donn\u00e9es Personnelles, \u00e0 savoir le droit de recevoir ses Donn\u00e9es Personnelles qui font l\u2019objet du Traitement dans un format exploitable et\/ou de demander \u00e0 ce que celles-ci soient transmises \u00e0 un autre Responsable de Traitement ;<\/li><li>Droit d\u2019opposition au Traitement de ses Donn\u00e9es Personnelles pour des motifs l\u00e9gitimes qui lui sont propres, sous r\u00e9serve de la cl\u00f4ture du Compte.<\/li><\/ul><p>Sauf dans le cas o\u00f9 la demande para\u00eet excessive ou si elle exige des efforts disproportionn\u00e9s, PHYSIDIA, en tant que de Responsable de Traitement, a l\u2019obligation de r\u00e9pondre aux demandes d\u2019exercice de droits des Utilisateurs dans les meilleurs d\u00e9lais et au plus tard un (1) mois apr\u00e8s r\u00e9ception de la demande.<\/p><h2>7. TRANSFERT DES DONNEES PERSONNELLES TRAITEES PAR PHYSIDIA<\/h2><p>La R\u00e9glementation Applicable encadre strictement et pr\u00e9cis\u00e9ment les transferts internationaux de Donn\u00e9es Personnelles.<\/p><p>PHYSIDIA s\u2019interdit tout transfert sans accord pr\u00e9alable de l\u2019Utilisateur et garanties appropri\u00e9es, afin que les Donn\u00e9es Personnelles des Utilisateurs soient correctement prot\u00e9g\u00e9es lorsqu\u2019elles sont transf\u00e9r\u00e9es vers un lieu situ\u00e9 en dehors de l\u2019Union europ\u00e9enne.<\/p><p>Les Donn\u00e9es collect\u00e9es par PHYSIDIA ne font l\u2019objet d\u2019aucun transfert vers un pays tiers et sont conserv\u00e9es au sein de l\u2019Espace Economique Europ\u00e9en (EEE).<\/p><h2>8. COOKIES ET TRACEURS<\/h2><p>Le Site utilise des cookies et autres traceurs, dont les modalit\u00e9s sont d\u00e9taill\u00e9es dans la politique de cookies accessible sur le Site. Le consentement de l\u2019Utilisateur est recueilli lorsque la r\u00e9glementation l\u2019exige.<\/p><h2>9. CONTACT<\/h2><p>Pour tous renseignements et questions relatifs \u00e0 la Politique ou les pratiques de PHYSIDIA en mati\u00e8re de protection des Donn\u00e9es Personnelles, merci d\u2019adresser un email \u00e0 l\u2019adresse suivante : <a href=\"mailto:dpo@physidia.fr\">dpo@physidia.fr<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique de confidentialit\u00e9 1. PREAMBULE La soci\u00e9t\u00e9 PHYSIDIA est une soci\u00e9t\u00e9 par actions simplifi\u00e9e, sp\u00e9cialis\u00e9e dans la dialyse \u00e0 domicile. La pr\u00e9sente politique de confidentialit\u00e9 (ci-apr\u00e8s la \u00ab Politique \u00bb) a pour objet d\u2019informer les utilisateurs (ci-apr\u00e8s d\u00e9sign\u00e9s \u00ab Utilisateurs \u00bb) du site internet www.nehomy.com (ci-apr\u00e8s le \u00ab Site \u00bb) sur les conditions de collecte et de traitement de leurs donn\u00e9es \u00e0 caract\u00e8re personnel (ci-apr\u00e8s les \u00ab\u00a0Donn\u00e9es Personnelles\u00a0\u00bb) dans le cadre de l\u2019utilisation du Site, y compris lorsque l\u2019Utilisateur cr\u00e9e un compte et renseigne certaines informations le concernant. Cette Politique a \u00e9t\u00e9 \u00e9labor\u00e9e de mani\u00e8re \u00e0 garantir que PHYSIDIA exerce ses activit\u00e9s conform\u00e9ment aux l\u00e9gislations nationales, europ\u00e9ennes et internationales relatives \u00e0 la protection des Donn\u00e9es Personnelles et, en particulier, le R\u00e8glement (UE) n\u00b0 2016\/679 du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-91","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Politique de Confidentialit\u00e9 - Physidia - H\u00e9modialyse \u00e0 Domicile<\/title>\n<meta name=\"description\" content=\"Politique de confidentialit\u00e9 Physidia : traitement des donn\u00e9es personnelles conforme au RGPD et \u00e0 la r\u00e9glementation en vigueur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nehomy.com\/en\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Politique de confidentialit\u00e9 Physidia : traitement des donn\u00e9es personnelles conforme au RGPD et \u00e0 la r\u00e9glementation en vigueur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nehomy.com\/en\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Nehomy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nehomy\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-19T15:12:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nehomy.com\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/nehomy.com\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de Confidentialit\u00e9 - Physidia - H\u00e9modialyse \u00e0 Domicile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nehomy.com\\\/#website\"},\"datePublished\":\"2024-12-18T15:45:09+00:00\",\"dateModified\":\"2026-03-19T15:12:58+00:00\",\"description\":\"Politique de confidentialit\u00e9 Physidia : traitement des donn\u00e9es personnelles conforme au RGPD et \u00e0 la r\u00e9glementation en vigueur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nehomy.com\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nehomy.com\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nehomy.com\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/nehomy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nehomy.com\\\/#website\",\"url\":\"https:\\\/\\\/nehomy.com\\\/\",\"name\":\"Nehomy | H\u00e9modialyse \u00e0 Domicile\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/nehomy.com\\\/#organization\"},\"alternateName\":\"Nehomy | HDDQ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nehomy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nehomy.com\\\/#organization\",\"name\":\"Nehomy\",\"alternateName\":\"Nehomy\",\"url\":\"https:\\\/\\\/nehomy.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/nehomy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nehomy.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/nehomy-favicon-32x32-1.svg\",\"contentUrl\":\"https:\\\/\\\/nehomy.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/nehomy-favicon-32x32-1.svg\",\"width\":1,\"height\":1,\"caption\":\"Nehomy\"},\"image\":{\"@id\":\"https:\\\/\\\/nehomy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nehomy\"],\"email\":\"contact@nehomy.com\",\"legalName\":\"Physidia S.A.S.\",\"foundingDate\":\"2010-11-01\",\"taxID\":\"528 454 028 00028\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/nehomy.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/nehomy.com\\\/politique-de-confidentialite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Politique de Confidentialit\u00e9 - Physidia - H\u00e9modialyse \u00e0 Domicile","description":"Politique de confidentialit\u00e9 Physidia : traitement des donn\u00e9es personnelles conforme au RGPD et \u00e0 la r\u00e9glementation en vigueur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nehomy.com\/en\/privacy-policy\/","og_locale":"en_GB","og_type":"article","og_title":"Politique de confidentialit\u00e9","og_description":"Politique de confidentialit\u00e9 Physidia : traitement des donn\u00e9es personnelles conforme au RGPD et \u00e0 la r\u00e9glementation en vigueur.","og_url":"https:\/\/nehomy.com\/en\/privacy-policy\/","og_site_name":"Nehomy","article_publisher":"https:\/\/www.facebook.com\/Nehomy","article_modified_time":"2026-03-19T15:12:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nehomy.com\/politique-de-confidentialite\/","url":"https:\/\/nehomy.com\/politique-de-confidentialite\/","name":"Politique de Confidentialit\u00e9 - Physidia - H\u00e9modialyse \u00e0 Domicile","isPartOf":{"@id":"https:\/\/nehomy.com\/#website"},"datePublished":"2024-12-18T15:45:09+00:00","dateModified":"2026-03-19T15:12:58+00:00","description":"Politique de confidentialit\u00e9 Physidia : traitement des donn\u00e9es personnelles conforme au RGPD et \u00e0 la r\u00e9glementation en vigueur.","breadcrumb":{"@id":"https:\/\/nehomy.com\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nehomy.com\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nehomy.com\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/nehomy.com\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/nehomy.com\/#website","url":"https:\/\/nehomy.com\/","name":"Nehomy | H\u00e9modialyse \u00e0 Domicile","description":"","publisher":{"@id":"https:\/\/nehomy.com\/#organization"},"alternateName":"Nehomy | HDDQ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nehomy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/nehomy.com\/#organization","name":"Nehomy","alternateName":"Nehomy","url":"https:\/\/nehomy.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/nehomy.com\/#\/schema\/logo\/image\/","url":"https:\/\/nehomy.com\/wp-content\/uploads\/2024\/12\/nehomy-favicon-32x32-1.svg","contentUrl":"https:\/\/nehomy.com\/wp-content\/uploads\/2024\/12\/nehomy-favicon-32x32-1.svg","width":1,"height":1,"caption":"Nehomy"},"image":{"@id":"https:\/\/nehomy.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nehomy"],"email":"contact@nehomy.com","legalName":"Physidia S.A.S.","foundingDate":"2010-11-01","taxID":"528 454 028 00028","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/nehomy.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/nehomy.com\/politique-de-confidentialite\/"}]}},"_links":{"self":[{"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/pages\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/comments?post=91"}],"version-history":[{"count":43,"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/pages\/91\/revisions"}],"predecessor-version":[{"id":8081,"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/pages\/91\/revisions\/8081"}],"wp:attachment":[{"href":"https:\/\/nehomy.com\/en\/wp-json\/wp\/v2\/media?parent=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}